{"id":1207,"date":"2024-01-30T14:25:17","date_gmt":"2024-01-30T14:25:17","guid":{"rendered":"http:\/\/nordesteinfo.com\/?p=1207"},"modified":"2024-01-30T14:25:18","modified_gmt":"2024-01-30T14:25:18","slug":"vendio-lo-robado-y-quedo-preso","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2024\/01\/30\/vendio-lo-robado-y-quedo-preso\/","title":{"rendered":"VENDI\u00d3 LO ROBADO Y QUED\u00d3 PRESO"},"content":{"rendered":"\n<p>Un muchacho de 20 a\u00f1os qued\u00f3 detenido vinculado a un delito por supuesto robo en una propiedad ubicada en la localidad de Esquina<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"762\" height=\"596\" src=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/01\/1344540w762h596c.jpg.webp\" alt=\"\" class=\"wp-image-1208\" srcset=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/01\/1344540w762h596c.jpg.webp 762w, https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/01\/1344540w762h596c.jpg-300x235.webp 300w\" sizes=\"(max-width: 762px) 100vw, 762px\" \/><\/figure>\n\n\n\n<p>&nbsp;Seg\u00fan pudo averiguar la Polic\u00eda tras la denuncia del hecho el pasado 25 de enero, el sospechoso sustrajo las pertenencias de una familia y luego vendi\u00f3 gran parte de los elementos.<\/p>\n\n\n\n<p>Las labores de investigaci\u00f3n de los efectivos permiti\u00f3 primero identificar y localizar al presunto delincuente.<\/p>\n\n\n\n<p>Tras esa diligencia comenzaron las tareas de ubicar el domicilio de las personas a quienes al parecer les vendi\u00f3 los objetos denunciados como robados.<\/p>\n\n\n\n<p>As\u00ed, lograron recuperar la totalidad de los elementos sustra\u00eddos gracias al gesto de colaboraci\u00f3n de estas personas que adquirieron los objetos de buena fe, evitando adem\u00e1s posibles consecuencias legales.<\/p>\n\n\n\n<p>El joven de apellido Ojeda qued\u00f3 a disposici\u00f3n de la fiscal\u00eda en turno y fue trasladado a la Comisar\u00eda Segunda donde realizaron las actuaciones del caso.<\/p>\n\n\n\n<p>El trabajo de los efectivos se dio gracias al aporte de testimonios an\u00f3nimos como el registro de algunas filmaciones de c\u00e1maras de seguridad de la zona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un muchacho de 20 a\u00f1os qued\u00f3 detenido vinculado a un delito por supuesto robo en<\/p>\n","protected":false},"author":1,"featured_media":1208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1207"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1207"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1207\/revisions"}],"predecessor-version":[{"id":1209,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1207\/revisions\/1209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1208"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}