{"id":1242,"date":"2024-02-26T14:19:20","date_gmt":"2024-02-26T14:19:20","guid":{"rendered":"http:\/\/nordesteinfo.com\/?p=1242"},"modified":"2024-02-26T14:19:22","modified_gmt":"2024-02-26T14:19:22","slug":"milei-contra-el-gobernador-de-chubut-no-puede-leer-un-contrato-el-pobre","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2024\/02\/26\/milei-contra-el-gobernador-de-chubut-no-puede-leer-un-contrato-el-pobre\/","title":{"rendered":"MILEI CONTRA EL GOBERNADOR DE CHUBUT: \u201cNO PUEDE LEER UN CONTRATO EL POBRE\u201d"},"content":{"rendered":"\n<p>Afirm\u00f3 que si cumple con su amenaza de cortar el suministro de petr\u00f3leo, \u00abpagar\u00e1\u00a0la consecuencias\u00bb.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"440\" src=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/02\/1708909629314.webp\" alt=\"\" class=\"wp-image-1243\" srcset=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/02\/1708909629314.webp 770w, https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/02\/1708909629314-300x171.webp 300w, https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/02\/1708909629314-768x439.webp 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/figure>\n\n\n\n<p>&nbsp;En medio de la pelea con la provincia de Chubut, que abri\u00f3 un fuerte conflicto entre la Naci\u00f3n y las provincias, el presidente Javier Milei volvi\u00f3 a chicanear al gobernador Ignacio Torres: lo trat\u00f3 de \u00abpobre chico\u00bb, dijo que no sabe leer un contrato y sostuvo que es una v\u00edctima del deterioro de la educaci\u00f3n en la Argentina. Adem\u00e1s, trat\u00f3 de \u00abpol\u00edticos runfla\u00bb a los mandatarios que lo apoyaron.<\/p>\n\n\n\n<p>\u00abPobrecito, Nachito, no la ve. Es un pobre chico que no puede leer un contrato. Es de una precariedad intelectual muy grande\u00bb, afirm\u00f3 el presidente desde Washington, en una entrevista telef\u00f3nica con el canal LN+.<\/p>\n\n\n\n<p>\u00abLa provincia tom\u00f3 deuda contra garant\u00eda de coparticipaci\u00f3n, cuando arma esa operaci\u00f3n hace que cuando le depositan la coparticipaci\u00f3n, se extrae la parte afectada a la deuda y le llega el remanente\u00bb, explic\u00f3 Milei antes de tomar el vuelo con el que llegar\u00e1 al pa\u00eds este lunes por la ma\u00f1ana.<\/p>\n\n\n\n<p>Luego volvi\u00f3 a atacar con dureza y en tono despectivo al gobernador patag\u00f3nico. \u00abNo tengo la culpa de que el chico no pueda leer un texto y comprenderlo, es una v\u00edctima del deterioro de la educaci\u00f3n en Argentina y no puede leer un contrato el pobre chico\u00bb, afirm\u00f3.<\/p>\n\n\n\n<p>Al ser consultado sobre el apoyo mayoritario de los mandatarios provinciales al reclamo de Torres, Milei dijo que eso \u00abhabla muy mal\u00bb de ellos, porque avalaron lo que \u00e9l calific\u00f3 como \u00abla mentira del gobernador de Chubut\u00bb. Y plante\u00f3 que eso los dej\u00f3 expuestos. \u00abQuedaron del mismo lado que (Axel) Kicillof y (Ricardo) Quintela\u00bb, en referencia a los mandatarios de Buenos Aires y La Rioja.<\/p>\n\n\n\n<p>\u00abEsos muchachos, que son parte del pasado. en el fondo est\u00e1n reclamando que no quieren ajustar y le quieren trasladar el ajuste al resto de los argentinos. Estamos para defender a los argentinos y no a los pol\u00edticos runfla\u00bb, afirm\u00f3.<\/p>\n\n\n\n<p>\u00abEs muy peligroso lo que hizo el resto de los gobernadores apoyando semejante disparate. Los gobernadores tienen que hacer un ajuste fiscal de un punto del PBI y no lo quieren hacer\u00bb, sostuvo y apunt\u00f3 a que \u00abno quieren perder sus privilegios de casta\u00bb.<\/p>\n\n\n\n<p>Ante la pregunta de si tiene previsto intervenir la provincia, en caso de que se concrete la amenaza de cortar el flujo de petr\u00f3leo, evit\u00f3 dar una definici\u00f3n concreta y dijo que se har\u00e1 lo que determine la Justicia.<\/p>\n\n\n\n<p>\u00abTomar\u00e1 acciones la Justicia. \u00bfQue alguien sea pol\u00edtico lo exime de cumplir la ley? Dentro de la ley todo, fuera de la ley nada. Si viola la ley, pagar\u00e1 las consecuencias\u00bb, dijo y luego agreg\u00f3: \u00abSe seguir\u00e1n los pasos legales que determinen la Justicia\u00bb.<\/p>\n\n\n\n<p>Jubilaciones<\/p>\n\n\n\n<p>El jefe de Estado tambi\u00e9n se refiri\u00f3 a las jubilaciones, luego de la \u00faltima actualizaci\u00f3n que se realiz\u00f3 el mi\u00e9rcoles que llev\u00f3 el valor el valor a un 27,18% a partir del mes de marzo, que llevar\u00e1 el haber bruto m\u00ednimo de $105.713 a $134.446 y el haber bruto m\u00e1ximo, de $711.346 a $904.690.<\/p>\n\n\n\n<p>\u00abCon Massa ganaban 80 d\u00f3lares, hoy ganan 200\u00bb, afirm\u00f3 durante el extenso reportaje. Y volvi\u00f3 a apuntar a \u00abla casta pol\u00edtica\u00bb por haber eliminado la f\u00f3rmula jubilatoria que estaba incluida en el proyecto de Ley \u00d3mnibus, que \u00abperjudicaron a los jubilados\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afirm\u00f3 que si cumple con su amenaza de cortar el suministro de petr\u00f3leo, \u00abpagar\u00e1\u00a0la consecuencias\u00bb.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":1243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1242"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1242"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1242\/revisions"}],"predecessor-version":[{"id":1244,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1242\/revisions\/1244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1243"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}