{"id":1284,"date":"2024-03-14T12:05:54","date_gmt":"2024-03-14T12:05:54","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1284"},"modified":"2024-04-05T12:30:41","modified_gmt":"2024-04-05T12:30:41","slug":"goya-videos-de-seguridad-confirman-que-joven-fallecido-venia-corriendo-en-una-picada","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2024\/03\/14\/goya-videos-de-seguridad-confirman-que-joven-fallecido-venia-corriendo-en-una-picada\/","title":{"rendered":"GOYA: VIDEOS DE SEGURIDAD CONFIRMAN QUE JOVEN FALLECIDO VEN\u00cdA CORRIENDO EN UNA PICADA"},"content":{"rendered":"\n<p>Los videos pesquisados por la Justicia habr\u00edan arrojado detalles valiosos para la investigaci\u00f3n y colocan a la v\u00edctima mortal, circulando a muy alta velocidad, en compa\u00f1\u00eda de otro sujeto que se dio a la fuga, luego del violento impacto contra el autom\u00f3vil.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"495\" src=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/04\/1285877w850h495c.jpg.webp\" alt=\"\" class=\"wp-image-1285\" srcset=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/04\/1285877w850h495c.jpg.webp 850w, https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/04\/1285877w850h495c.jpg-300x175.webp 300w, https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/04\/1285877w850h495c.jpg-768x447.webp 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p>&nbsp;Fuentes consultadas por diario \u00e9poca indicaron que \u00abAranda vendr\u00eda corriendo picadas junto con otro sujeto, cuando repentinamente impact\u00f3 contra el Volkswagen Bora azul sobre la traza de la Ruta Provincial N\u00b027, frente al santuario del \u2018Cura Brochero\u2019. El otro sujeto huy\u00f3\u00bb.<\/p>\n\n\n\n<p>Si bien se pudo establecer esta situaci\u00f3n, las im\u00e1genes no alcanzan a revelar si una mala maniobra de los motociclistas fue lo que termin\u00f3 enviando a Aranda contra el auto, o si por el contrario fue \u00e9ste el que se meti\u00f3 en el carril de la v\u00edctima. Este dato lo arrojar\u00e1n las otras pericias realizadas por planimetristas de la Polic\u00eda y quienes realizar\u00e1n un an\u00e1lisis de los dos veh\u00edculos involucrados en el siniestro.<\/p>\n\n\n\n<p>Ayer, fuentes indicaron que el conductor del autom\u00f3vil, de apellido Villa, contin\u00faa internado, ya que tiene los dos ojos comprometidos, producto del impacto de la v\u00edctima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los videos pesquisados por la Justicia habr\u00edan arrojado detalles valiosos para la investigaci\u00f3n y colocan<\/p>\n","protected":false},"author":1,"featured_media":1285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1284"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1284"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1284\/revisions"}],"predecessor-version":[{"id":1286,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1284\/revisions\/1286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1285"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}