{"id":1297,"date":"2024-03-14T12:10:38","date_gmt":"2024-03-14T12:10:38","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1297"},"modified":"2024-04-05T12:30:02","modified_gmt":"2024-04-05T12:30:02","slug":"crece-la-demanda-turistica-de-corrientes-como-destino-nacional-propuestas-para-un-sector-clave-en-el-desarrollo-de-la-ciudad","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2024\/03\/14\/crece-la-demanda-turistica-de-corrientes-como-destino-nacional-propuestas-para-un-sector-clave-en-el-desarrollo-de-la-ciudad\/","title":{"rendered":"CRECE LA DEMANDA TUR\u00cdSTICA DE CORRIENTES COMO DESTINO NACIONAL PROPUESTAS PARA UN SECTOR CLAVE EN EL DESARROLLO DE LA CIUDAD"},"content":{"rendered":"\n<p><em>La oficina de la municipalidad recibi\u00f3 esta ma\u00f1ana a una delegaci\u00f3n de periodistas de medios nacionales e internacionales que visitan Corrientes para conocer la propuesta tur\u00edstica de la ciudad y promocionarla como destino emergente. Tambi\u00e9n se reuni\u00f3 con empresarios del rubro de Chaco para potenciar la unidad entre ambas provincias. \u00a0<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/04\/4a306398-60eb-de3f-76ac-e69fee043760-1024x682.jpeg\" alt=\"\" class=\"wp-image-1298\" srcset=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/04\/4a306398-60eb-de3f-76ac-e69fee043760-1024x682.jpeg 1024w, https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/04\/4a306398-60eb-de3f-76ac-e69fee043760-300x200.jpeg 300w, https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/04\/4a306398-60eb-de3f-76ac-e69fee043760-768x512.jpeg 768w, https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/04\/4a306398-60eb-de3f-76ac-e69fee043760.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>El intendente Eduardo Tassano mantuvo un encuentro con periodistas, trabajadores de medios y empresarios tur\u00edsticos chaque\u00f1os, donde charlaron sobre la oferta tur\u00edstica de la ciudad, su potencial para ampliarse y los proyectos a futuro. Particularmente se abordaron las distintas oportunidades que ofrece tener la temporada de playa m\u00e1s extensa del pa\u00eds, que va de octubre a abril y permite seis meses de eventos art\u00edsticos al aire libre, deportes acu\u00e1ticos, gastronom\u00eda a la vera del r\u00edo, y de clima c\u00e1lido para caminatas nocturnas por la ciudad.<br>Adem\u00e1s, abordaron los circuitos para recorrer la ciudad que ya se encuentran en marcha, como ser el paseo mitol\u00f3gico, el paseo religioso, el correntino, de los murales y las visitas por el d\u00eda a los esteros del iber\u00e1 para disfrutar de una jornada de pesca. Respecto a esto \u00faltimo, la delegaci\u00f3n de periodistas visit\u00f3 Paso de la Patria y el Iber\u00e1 junto con representantes del Ministerio de Turismo de la Provincia, el secretario de Turismo y Deporte de la ciudad Juan Enrique Braillard Poccard y funcionarios del \u00e1rea, que oficiaron de anfitriones. Todas las partes coincidieron en la capacidad que el sector demostr\u00f3 para generar consumo, producci\u00f3n y trabajo correntino, que en el primer trimestre del a\u00f1o destac\u00f3 gracias a los carnavales y el festival del chamam\u00e9.<br>El grupo de representantes de diversos medios estuvo integrado por: Mar\u00eda Florencia Ferrero, de Canal 12 de C\u00f3rdoba (Arriba C\u00f3rdoba) e influencer; Carola Cinto, de la revista Flybondi y La Voz del Interior (Buenos Aires &#8211; C\u00f3rdoba); Joan Biosca Capdevila, corresponsal Tv3 de Espa\u00f1a &#8211; Catalu\u00f1a Radio de Barcelona; Alejandro Dar\u00edo Nogueira, Tv3 (camar\u00f3grafo).<br>Tambi\u00e9n formaron parte Diego Ricardo Jemio, del diario Clar\u00edn Viajes (Buenos Aires); Carina Costello, diario El Tribuno de Salta; y Jos\u00e9 Pablo Ceriales, del diario El Pa\u00eds de Espa\u00f1a.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La oficina de la municipalidad recibi\u00f3 esta ma\u00f1ana a una delegaci\u00f3n de periodistas de medios<\/p>\n","protected":false},"author":1,"featured_media":1298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1297"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1297"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1297\/revisions"}],"predecessor-version":[{"id":1299,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1297\/revisions\/1299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1298"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}