{"id":1412,"date":"2024-06-25T23:30:00","date_gmt":"2024-06-25T23:30:00","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1412"},"modified":"2024-06-25T23:30:00","modified_gmt":"2024-06-25T23:30:00","slug":"desmantelaron-una-red-de-facturas-apocrifas-en-goya","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2024\/06\/25\/desmantelaron-una-red-de-facturas-apocrifas-en-goya\/","title":{"rendered":"DESMANTELARON UNA RED DE FACTURAS AP\u00d3CRIFAS EN GOYA"},"content":{"rendered":"\n<p>La organizaci\u00f3n operaba desde 2019 hasta 2022, evadiendo m\u00e1s de 85 millones de pesos argentinos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"461\" src=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/06\/397794.jpeg_nota.jpeg\" alt=\"\" class=\"wp-image-1413\" srcset=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/06\/397794.jpeg_nota.jpeg 700w, https:\/\/nordesteinfo.com\/wp-content\/uploads\/2024\/06\/397794.jpeg_nota-300x198.jpeg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<p>En un operativo llevado a cabo por el Grupo de Delitos Econ\u00f3micos y Financieros, dependiente de la Unidad de Investigaciones de Delitos Complejos y Procedimientos Judiciales \u00abGoya\u00bb, se logr\u00f3 desbaratar una organizaci\u00f3n dedicada a la emisi\u00f3n de facturas ap\u00f3crifas en la provincia de Corrientes.\u00a0<\/p>\n\n\n\n<p>La investigaci\u00f3n, que estuvo a cargo del Juzgado Federal de Goya, revel\u00f3 que la red operaba desde los a\u00f1os 2019 hasta 2022, evadiendo m\u00e1s de 85 millones de pesos argentinos.<\/p>\n\n\n\n<p>Seg\u00fan las pesquisas, la organizaci\u00f3n hab\u00eda generado numerosos comprobantes falsos durante ese periodo. Tras meses de trabajo de campo, se determin\u00f3 que el denunciante inicialmente reportado como v\u00edctima era en realidad el emisor de estas facturas fraudulentas.<\/p>\n\n\n\n<p>En los allanamientos realizados en la provincia, se secuestraron importantes sumas de dinero en efectivo, as\u00ed como d\u00f3lares, veh\u00edculos de lujo, una escopeta, dispositivos electr\u00f3nicos y documentaci\u00f3n relevante para la causa. El aval\u00fao de los elementos incautados supera los 90 millones de pesos.<\/p>\n\n\n\n<p>Un ciudadano qued\u00f3 supeditado a la causa por presunta evasi\u00f3n fiscal, falsificaci\u00f3n de documentos y fraude tributario. En el operativo tambi\u00e9n participaron efectivos de la Agrupaci\u00f3n III \u00abCorrientes\u00bb y personal de AFIP-DGI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n operaba desde 2019 hasta 2022, evadiendo m\u00e1s de 85 millones de pesos argentinos.<\/p>\n","protected":false},"author":1,"featured_media":1413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1412"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1412"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1412\/revisions"}],"predecessor-version":[{"id":1414,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1412\/revisions\/1414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1413"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}