{"id":1483,"date":"2024-09-27T14:22:09","date_gmt":"2024-09-27T14:22:09","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1483"},"modified":"2024-09-27T14:22:09","modified_gmt":"2024-09-27T14:22:09","slug":"dengue-la-lucha-mas-importante-hoy-es-contra-el-mosquito","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2024\/09\/27\/dengue-la-lucha-mas-importante-hoy-es-contra-el-mosquito\/","title":{"rendered":"DENGUE: \u00abLA LUCHA M\u00c1S IMPORTANTE HOY ES CONTRA EL MOSQUITO\u00bb"},"content":{"rendered":"\n<p>El ministro de Salud P\u00fablica Ricardo Cardozo habl\u00f3 con Radio Sudamericana en relaci\u00f3n a la vacunaci\u00f3n contra el virus del dengue en Corrientes, asegurando que se est\u00e1n aplicando vacunas y esperando que la empresa productora env\u00ede m\u00e1s dosis. En este marco, tambi\u00e9n pidi\u00f3 a los padres que lleven a sus hijos a aplicar las vacunas, dado que \u201chay algunas que est\u00e1n atrasadas en el calendario\u201d. \u00a0<\/p>\n\n\n\n<p>El ministro de Salud P\u00fablica de la Provincia de Corrientes, Dr. Ricardo Cardozo habl\u00f3 al respecto de la aplicaci\u00f3n de vacunas contra el dengue, recordando que se est\u00e1 desarrollando el cronograma en Corrientes. Explic\u00f3 que con el regreso del calor a la regi\u00f3n \u201cest\u00e1 aumentando la demanda\u201d, pero hizo hincapi\u00e9 en la importancia de la prevenci\u00f3n.<\/p>\n\n\n\n<p>En este sentido, record\u00f3 que \u201chay dificultades con la empresa productora, que se qued\u00f3 sin dosis\u201d, pero reiter\u00f3 que \u201cla decisi\u00f3n del Gobierno es comprar m\u00e1s dosis, pero estamos atentos\u201d. Afirm\u00f3, en este marco, que \u201choy la batalla contra el vector es m\u00e1s importante que la vacunaci\u00f3n\u201d y reiter\u00f3 que \u201cpor eso hay que disminuir la cantidad de criaderos\u201d.<\/p>\n\n\n\n<p>Hay que considerar que el mosquito del dengue, el Aedes Aegipty se cr\u00eda especialmente en los hogares, en cada dep\u00f3sito de agua que encuentre y donde pueda depositar sus huevos. Los mosquitos pican a pacientes enfermos y llevan el virus a pacientes sanos, propagando la enfermedad, por eso es importante que se eliminen los criaderos para reducir los contagios.<\/p>\n\n\n\n<p>En cuanto al resto de las vacunas, el ministro Cardozo record\u00f3 que se est\u00e1 intensificando la aplicaci\u00f3n de dosis que previenen otras enfermedades. Llam\u00f3, en este marco, a los padres a completar el calendario de vacunaci\u00f3n de sus hijos, dado que hubo un descenso en el cumplimiento desde que se produjo la pandemia de Covid-19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Salud P\u00fablica Ricardo Cardozo habl\u00f3 con Radio Sudamericana en relaci\u00f3n a la<\/p>\n","protected":false},"author":1,"featured_media":1484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1483"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1483"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1483\/revisions"}],"predecessor-version":[{"id":1485,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1483\/revisions\/1485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1484"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}