{"id":1531,"date":"2024-11-20T02:25:02","date_gmt":"2024-11-20T02:25:02","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1531"},"modified":"2024-11-26T02:27:51","modified_gmt":"2024-11-26T02:27:51","slug":"internaron-de-urgencia-al-presidente-de-paraguay-santiago-pena","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2024\/11\/20\/internaron-de-urgencia-al-presidente-de-paraguay-santiago-pena\/","title":{"rendered":"INTERNARON DE URGENCIA AL PRESIDENTE DE PARAGUAY, SANTIAGO PE\u00d1A"},"content":{"rendered":"\n<p>El mandatario sufri\u00f3 un dolor en el pecho mientras participaba del encuentro en R\u00edo de Janeiro. \u201cSu estado de salud es estable\u201d, detall\u00f3 el parte m\u00e9dico difundido por la cl\u00ednica donde fue atendido.<\/p>\n\n\n\n<p>El presidente de Paraguay,&nbsp;Santiago Pe\u00f1a,&nbsp;sufri\u00f3 un dolor en el pecho mientras participaba de la&nbsp;cumbre del G20&nbsp;en R\u00edo de Janeiro y fue hospitalizado de urgencia. \u201cSu estado es estable\u201d, inform\u00f3 la cl\u00ednica Samaritano, donde se encuentra el mandatario.<\/p>\n\n\n\n<p>Pe\u00f1a empez\u00f3 a sentir esa molestia en el Museo de Arte Moderno, donde le realizaron un electrocardiograma. Los resultados alertaron a los m\u00e9dicos y se decidi\u00f3 que sea internado.<\/p>\n\n\n\n<p>El ministro de Tecnolog\u00edas de la Informaci\u00f3n y la Comunicaci\u00f3n de Paraguay, Gustavo Villate, inform\u00f3 que Pe\u00f1a&nbsp;\u201cse encuentra bien\u201d.<\/p>\n\n\n\n<p>\u201cEl paciente present\u00f3 malestar en el per\u00edodo de la tarde y, por seguridad, acudi\u00f3 al hospital para realizar ex\u00e1menes de diagn\u00f3stico.&nbsp;El jefe de Estado est\u00e1 bien y su estado de salud actual es estable\u201d,&nbsp;se\u00f1al\u00f3 el informe de la cl\u00ednica.<\/p>\n\n\n\n<p>Pe\u00f1a viaj\u00f3 el domingo a R\u00edo de Janeiro, donde particip\u00f3 del c\u00f3nclave de l\u00edderes del G20 que tendr\u00e1 lugar hasta este martes. Entre los&nbsp;objetivos de la cumbre estaban&nbsp;la coordinaci\u00f3n de pol\u00edticas para lograr la estabilidad econ\u00f3mica mundial y el crecimiento sostenible; la promoci\u00f3n de regulaciones financieras que permitan disminuir el riesgo y prevenir nuevas crisis; y el redise\u00f1o de la arquitectura financiera internacional.<\/p>\n\n\n\n<p>El mandatario asumi\u00f3 a su cargo en agosto de 2023, con tan solo 45 a\u00f1os, convirti\u00e9ndose en&nbsp;el presidente m\u00e1s joven de la era democr\u00e1tica del pa\u00eds sudamericano, despu\u00e9s de la ca\u00edda de la dictadura de Alfredo Stroessner (1954-1989).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mandatario sufri\u00f3 un dolor en el pecho mientras participaba del encuentro en R\u00edo de<\/p>\n","protected":false},"author":1,"featured_media":1532,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1531"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1531"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1531\/revisions"}],"predecessor-version":[{"id":1533,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1531\/revisions\/1533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1532"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}