{"id":1534,"date":"2024-11-20T02:26:30","date_gmt":"2024-11-20T02:26:30","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1534"},"modified":"2024-11-26T02:27:46","modified_gmt":"2024-11-26T02:27:46","slug":"la-seleccion-recibe-a-peru-en-busca-de-cerrar-el-ano-con-una-victoria","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2024\/11\/20\/la-seleccion-recibe-a-peru-en-busca-de-cerrar-el-ano-con-una-victoria\/","title":{"rendered":"LA SELECCI\u00d3N RECIBE A PER\u00da, EN BUSCA DE CERRAR EL A\u00d1O CON UNA VICTORIA"},"content":{"rendered":"\n<p>El conjunto de Lionel Scaloni busca recuperarse de la reciente derrota ante Paraguay y terminar el a\u00f1o liderando las Eliminatorias.<\/p>\n\n\n\n<p>Tras la derrota en su visita a&nbsp;Paraguay, la&nbsp;Selecci\u00f3n Argentina&nbsp;recibe este martes a&nbsp;Per\u00fa&nbsp;por la fecha 12, con el objetivo de cerrar el a\u00f1o asegurando el primer lugar en la tabla de las&nbsp;Eliminatorias Sudamericanas.<\/p>\n\n\n\n<p>El partido se disputa desde las 21 horas en la Bombonera, con arbitraje de&nbsp;Wilmar Rold\u00e1n&nbsp;y&nbsp;Yadir Acu\u00f1a&nbsp;en el VAR, y televisaci\u00f3n de&nbsp;Telefe&nbsp;y&nbsp;TyC Sports.<\/p>\n\n\n\n<p>El conjunto argentino llega l\u00edder,&nbsp;con tres puntos de ventaja sobre los escoltas Colombia y Uruguay, pese a la reciente derrota del jueves en Asunci\u00f3n ante el conjunto de&nbsp;Gustavo Alfaro.<\/p>\n\n\n\n<p>Para este compromiso, el entrenador&nbsp;Lionel Scaloni&nbsp;deber\u00e1 rearmar el equipo debido a las recientes bajas que sufri\u00f3 el plantel por diversas lesiones. Con Nahuel Molina y Cuti Romero desafectados, el DT&nbsp;s\u00ed confirm\u00f3 a Nicol\u00e1s Tagliafico, quien ven\u00eda con algunas dolencias.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de la floja actuaci\u00f3n en&nbsp;Paraguay,&nbsp;es muy probable que el t\u00e9cnico repita al resto del equipo, con el tridente de&nbsp;Lionel Messi,&nbsp;Lautaro Mart\u00ednez&nbsp;y&nbsp;Juli\u00e1n \u00c1lvarez&nbsp;en la delantera.<\/p>\n\n\n\n<p>En cuanto a la visita, llega a esta jornada pen\u00faltimo en la tabla de posiciones, solo por encima de Chile y a cinco unidades de Venezuela, por ahora el equipo que se encuentra en repechaje. B<\/p>\n\n\n\n<p>ajo la conducci\u00f3n del uruguayo&nbsp;Jorge Fossati, viene de igualar de local 0-0 con el conjunto trasandino en el \u00abCl\u00e1sico del Pac\u00edfico\u00bb, y en la pasada doble fecha de Eliminatorias, sufri\u00f3 una goleada ante Brasil pero le gan\u00f3 a Uruguay, en su \u00fanica victoria hasta el momento.<\/p>\n\n\n\n<p><strong>Seguir Leyendo:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.radiosudamericana.com\/nota\/deportes\/318426-Una-pareja-se-hizo-viral-por-un-tenso-momento-en-la-cancha-de-Gimnasia.htm\" target=\"_blank\" rel=\"noreferrer noopener\">Una pareja se hizo viral por un tenso momento en la cancha de Gimnasia<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.radiosudamericana.com\/nota\/deportes\/318437-Andrea-y-Esteban--los-correntinos-que-vieron-campeon-a-Racing.htm\" target=\"_blank\" rel=\"noreferrer noopener\">Andrea y Esteban, los correntinos que vieron campe\u00f3n a Racing<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Probables formaciones de Argentina vs Paraguay por las Eliminatorias<\/strong><\/h2>\n\n\n\n<p><strong>Argentina:<\/strong>&nbsp;Dibu&nbsp;Mart\u00ednez;&nbsp;Gonzalo&nbsp;Montiel,&nbsp;Nicol\u00e1s&nbsp;Otamendi,&nbsp;Leonardo&nbsp;Balerdi,&nbsp;Nicol\u00e1s&nbsp;Tagliafico;&nbsp;Rodrigo&nbsp;De Paul,&nbsp;Alexis&nbsp;Mac Allister,&nbsp;Enzo&nbsp;Fern\u00e1ndez; Lionel&nbsp;Messi,&nbsp;Juli\u00e1n&nbsp;\u00c1lvarez&nbsp;y Lautaro&nbsp;Mart\u00ednez.&nbsp;DT: Lionel&nbsp;Scaloni.<\/p>\n\n\n\n<p><strong>Per\u00fa:<\/strong>&nbsp;Pedro&nbsp;Gallese;&nbsp;Carlos&nbsp;Zambrano&nbsp;o Aldo&nbsp;Cardozo, Miguel&nbsp;Araujo,&nbsp;Alexander&nbsp;Callens; Andy&nbsp;Polo,&nbsp;Oliver&nbsp;Sonne,&nbsp;Sergio&nbsp;Pe\u00f1a,&nbsp;Luis&nbsp;Adv\u00edncula,&nbsp;Jes\u00fas&nbsp;Castillo&nbsp;u Horacio&nbsp;Calcaterra;&nbsp;Paolo&nbsp;Guerrero&nbsp;y Alex&nbsp;Valera&nbsp;o Bryan&nbsp;Reyna.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>C\u00f3mo ver en vivo Argentina vs Per\u00fa por las Eliminatorias<\/strong><\/h2>\n\n\n\n<p>El partido ser\u00e1 transmitido por&nbsp;Telefe, TyC Sports y TV P\u00fablica. Adem\u00e1s, se podr\u00e1 seguir desde cualquier dispositivo m\u00f3vil a trav\u00e9s de las aplicaciones&nbsp;de Flow, Directv Go y Telecentro Play. Y a trav\u00e9s de MiTelefe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Otros datos de Argentina vs Per\u00fa<\/strong><\/h2>\n\n\n\n<p>Hora: 21.00<br>TV: TyC Sports<br>\u00c1rbitro: Wilmar Rold\u00e1n<br>VAR: Yadir Acu\u00f1a<br>AVAR: Heider Castro<br>Estadio: La Bombonera, La Boca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El conjunto de Lionel Scaloni busca recuperarse de la reciente derrota ante Paraguay y terminar<\/p>\n","protected":false},"author":1,"featured_media":1535,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1534"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1534"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1534\/revisions"}],"predecessor-version":[{"id":1536,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1534\/revisions\/1536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1535"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}