{"id":1550,"date":"2024-12-03T15:52:52","date_gmt":"2024-12-03T15:52:52","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1550"},"modified":"2024-12-03T15:52:53","modified_gmt":"2024-12-03T15:52:53","slug":"caso-loan-aseguran-que-habria-elementos-suficientes-para-ir-a-juicio-y-conocer-los-autores-de-la-desaparicion","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2024\/12\/03\/caso-loan-aseguran-que-habria-elementos-suficientes-para-ir-a-juicio-y-conocer-los-autores-de-la-desaparicion\/","title":{"rendered":"CASO LOAN: ASEGURAN QUE HABR\u00cdA ELEMENTOS SUFICIENTES PARA IR A JUICIO Y CONOCER LOS AUTORES DE LA DESAPARICI\u00d3N"},"content":{"rendered":"\n<p>El abogado que representa a dos de los detenidos por la desaparici\u00f3n de Loan asegur\u00f3 que hay pruebas para conocer a los autores e ir a juicio.<\/p>\n\n\n\n<p>Marcelo Hanson, abogado de Daniel \u00abFierrito\u00bb Ramirez y M\u00f3nica Millapi, afirm\u00f3 este lunes en exclusiva para A24 que \u00abhabr\u00eda elementos para llegar a un juicio\u00bb en el caso por la desaparici\u00f3n de Loan y asegur\u00f3 adem\u00e1s que \u00abhay pruebas pendientes que podr\u00edan corroborar\u00bb qui\u00e9nes son los autores del crimen.<br>&nbsp;<br>\u00abEn el delito de sustracci\u00f3n y ocultamiento habr\u00eda elementos, en principio por lo menos, para llegar a un juicio y hay pruebas pendientes que podr\u00edan corrobar los autores\u00bb, indic\u00f3 Hanson en A24.<br>&nbsp;<br>&nbsp;<br>Y agreg\u00f3: \u00abHay pericias ordenadas que no s\u00e9 por qu\u00e9 se dejaron para \u00faltimo momento. Hay elementos que van a ir aclarando el panorama de qui\u00e9nes tienen responsabilidad\u00bb.<\/p>\n\n\n\n<p>&nbsp;<br>Asimismo, consider\u00f3 que al aparecer algunas certezas, a trav\u00e9s de estas pericias, se \u00abva a obligar a que los que saben algo del tema hablen\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Drenar la laguna para encontrar rastros de Loan<\/h3>\n\n\n\n<p><br>Respecto a la posibiliad de drenar la laguna donde podr\u00eda haber rastros de Loan, el abogado se\u00f1al\u00f3 que \u00abtodav\u00eda no se orden\u00f3 el drenaje de la laguna\u00bb, sino que \u00abla jueza pidi\u00f3 un informe al Estado provincial de la factibilidad de realizarlo\u00bb.<\/p>\n\n\n\n<p>En esos informes, \u00absugieren que previamente se hagan otros estudios y no garantizan que se pueda hacer porque las lagunas est\u00e1n conectadas a trav\u00e9s de napas y es una tarea delicada\u00bb, marc\u00f3 Hanson.<\/p>\n\n\n\n<p>&nbsp;<br>\u00abTambi\u00e9n corresponde un informe de fauna y flora porque va a verse afectada\u00bb, agreg\u00f3.<\/p>\n\n\n\n<p>Sin embargo, advirti\u00f3 que si se llegara a hacer \u00abel drenaje, se pedir\u00eda para descartar que no haya nada ah\u00ed, pero habr\u00eda que analizar los costos para ver qu\u00e9 beneficios trae para la causa\u00bb.<\/p>\n\n\n\n<p>\u00abPonele que aparece algo en la laguna, no nos va a decir m\u00e1s que que termin\u00f3 ah\u00ed pero el tema es c\u00f3mo, puede ser que se haya perdido y haya tenido ese tr\u00e1gico final solo\u00bb, se\u00f1al\u00f3 el letrado.<\/p>\n\n\n\n<p>Tambi\u00e9n consider\u00f3 queb \u00abhay m\u00e1s dudas que certezas a seis meses de la desaparici\u00f3n de Loan\u00bb y llam\u00f3 la atenci\u00f3n sobre \u00abla cantidad de personal policial que intervino, se echan la culpa entre fuerzas policiales\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El abogado que representa a dos de los detenidos por la desaparici\u00f3n de Loan asegur\u00f3<\/p>\n","protected":false},"author":1,"featured_media":1551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1550"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1550"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1550\/revisions"}],"predecessor-version":[{"id":1552,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1550\/revisions\/1552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1551"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}