{"id":1587,"date":"2025-02-17T15:01:49","date_gmt":"2025-02-17T15:01:49","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1587"},"modified":"2025-02-17T15:01:50","modified_gmt":"2025-02-17T15:01:50","slug":"motociclista-sufrio-fracturas-tras-chocar-con-un-camion-en-ruta-12","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2025\/02\/17\/motociclista-sufrio-fracturas-tras-chocar-con-un-camion-en-ruta-12\/","title":{"rendered":"MOTOCICLISTA SUFRI\u00d3 FRACTURAS TRAS CHOCAR CON UN CAMI\u00d3N EN RUTA 12"},"content":{"rendered":"\n<p>El siniestro ocurri\u00f3 pasado el mediod\u00eda del viernes en la intersecci\u00f3n de Ruta 12 y Cazadores Correntinos. El conductor de la moto fue trasladado al Hospital Escuela con fracturas.<\/p>\n\n\n\n<p>Un nuevo accidente de tr\u00e1nsito se produjo pasado el mediod\u00eda de este viernes en la intersecci\u00f3n de la Ruta Nacional 12 y la avenida Cazadores Correntinos, en Corrientes. Un&nbsp;<strong>cami\u00f3n de encomiendas y una motocicleta colisionaron,<\/strong>&nbsp;dejando como saldo al conductor del rodado menor con fracturas.<\/p>\n\n\n\n<p>El motociclista fue asistido en el lugar por personal de emergencia y posteriormente trasladado al Hospital Escuela, donde recibi\u00f3 atenci\u00f3n m\u00e9dica. Hasta el cierre de esta nota, no se conoc\u00edan detalles sobre su estado de salud, ni las circunstancias exactas del siniestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El siniestro ocurri\u00f3 pasado el mediod\u00eda del viernes en la intersecci\u00f3n de Ruta 12 y<\/p>\n","protected":false},"author":1,"featured_media":1588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1587"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1587"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1587\/revisions"}],"predecessor-version":[{"id":1589,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1587\/revisions\/1589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1588"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}