{"id":1594,"date":"2025-03-27T11:42:14","date_gmt":"2025-03-27T11:42:14","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1594"},"modified":"2025-03-27T11:42:15","modified_gmt":"2025-03-27T11:42:15","slug":"estudiantes-sanluisenos-crearon-un-monumento-a-las-madres-de-los-soldados-caidos-en-malvinas","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2025\/03\/27\/estudiantes-sanluisenos-crearon-un-monumento-a-las-madres-de-los-soldados-caidos-en-malvinas\/","title":{"rendered":"ESTUDIANTES SANLUISE\u00d1OS CREARON UN MONUMENTO A LAS MADRES DE LOS SOLDADOS CA\u00cdDOS EN MALVINAS"},"content":{"rendered":"\n<p>Morena Dom\u00ednguez y F\u00e1tima Sotomayor, junto a otros cuatro compa\u00f1eros del Colegio secundario de San Luis del Palmar impulsaron la creaci\u00f3n de una escultura a las madres de los combatientes de Malvinas. La obra se encuentra en el Paseo de Malvinas, en San Luis del Palmar, y fue dise\u00f1ada por un joven artista local<a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.radiosudamericana.com%2Fnota%2Fsociedad%2F324466-Estudiantes-sanluisenos-crearon-un-monumento-a-las-madres-de-los-soldados-caidos-en-Malvinas.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>En el coraz\u00f3n del Paseo de Malvinas de San Luis del Palmar, un monumento se alza como s\u00edmbolo del amor y la resistencia de aquellas mujeres que vieron partir a sus hijos hacia la guerra sin la certeza de su regreso. Dos de las alumnas dialogaron con Canal 5TV y contaron sobre la obra.<\/p>\n\n\n\n<p>La escultura, dise\u00f1ada por el estudiante Santino Fr\u00edas Barrios y materializada con la ayuda del escultor Alfredo Ram\u00edrez, fue impulsada por un grupo de j\u00f3venes del Colegio Secundario de San Luis del Palmar,&nbsp;entre ellas Morena Dom\u00ednguez y F\u00e1tima Sotomayor, quienes hoy contin\u00faan su camino en la universidad.<\/p>\n\n\n\n<p>El proyecto naci\u00f3 como una actividad escolar en su \u00faltimo a\u00f1o de secundaria, cuando debieron elegir un tema de relevancia cultural. \u00abQuer\u00edamos destacar el rol de las mujeres en la guerra, pero al investigar nos dimos cuenta de que no hab\u00eda registros de sanluise\u00f1as que hubieran participado directamente en Malvinas. Por eso decidimos rendir homenaje a las madres de los ca\u00eddos, y en ellas, a todas las mujeres que sostuvieron a sus familias en esos tiempos tan dif\u00edciles\u00bb, explicaron.<\/p>\n\n\n\n<p>El Paseo de Malvinas, donde est\u00e1 emplazada la escultura, es un sitio donde se encuentran otras placas y monumentos en honor a los 52 soldados sanluise\u00f1os que combatieron en la guerra. Aunque el n\u00famero exacto de ca\u00eddos sigue en revisi\u00f3n debido a registros migratorios, el espacio se mantiene como un punto de encuentro para la memoria y el reconocimiento a los veteranos y sus familias.<\/p>\n\n\n\n<p>Si bien Morena y F\u00e1tima no tienen familiares directos que hayan combatido en Malvinas, el acercamiento al tema las llev\u00f3 a conocer de cerca la historia de los veteranos locales. \u00abDurante el proceso de investigaci\u00f3n, una de nuestras compa\u00f1eras descubri\u00f3 que un veterano que participa en las reuniones del centro de excombatientes era su t\u00edo, algo que no sab\u00eda hasta ese momento\u00bb, cont\u00f3 Morena.<\/p>\n\n\n\n<p>A pesar de haber iniciado su vida universitaria \u2014F\u00e1tima estudia Fonoaudiolog\u00eda y Morena Bioqu\u00edmica\u2014, ambas expresaron su deseo de seguir participando en los actos conmemorativos del 2 de abril. \u00abNos gustar\u00eda que el homenaje oficial en San Luis del Palmar se haga en el Paseo de Malvinas, porque es un lugar especial, cargado de historia y memoria\u00bb, afirmaron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morena Dom\u00ednguez y F\u00e1tima Sotomayor, junto a otros cuatro compa\u00f1eros del Colegio secundario de San<\/p>\n","protected":false},"author":1,"featured_media":1596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1594"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1594"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1594\/revisions"}],"predecessor-version":[{"id":1597,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1594\/revisions\/1597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1596"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}