{"id":1618,"date":"2025-04-19T08:20:38","date_gmt":"2025-04-19T08:20:38","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1618"},"modified":"2025-04-19T08:20:38","modified_gmt":"2025-04-19T08:20:38","slug":"hay-mas-de-6-denuncias-por-dia-de-ninos-y-adolescentes-desaparecidos","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2025\/04\/19\/hay-mas-de-6-denuncias-por-dia-de-ninos-y-adolescentes-desaparecidos\/","title":{"rendered":"HAY M\u00c1S DE 6 DENUNCIAS POR D\u00cdA DE NI\u00d1OS Y ADOLESCENTES DESAPARECIDOS"},"content":{"rendered":"\n<p>A poco de cumplirse un a\u00f1o de la desaparici\u00f3n de Loan Pe\u00f1a, la ONG destac\u00f3 el dato alarmante sobre el extrav\u00edo de chicos. La importancia de alertar durante \u201cla hora de oro\u201d<a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.radiosudamericana.com%2Fnota%2Fpoliciales%2F325613-Hay-mas-de-6-denuncias-por-dia-de-ninos-y-adolescentes-desaparecidos.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>La titular de la organizaci\u00f3n&nbsp;Missing Children&nbsp;Argentina,&nbsp;Ana Rosa Llobet, expres\u00f3 su preocupaci\u00f3n ante la constante cantidad de denuncias por extrav\u00edo de ni\u00f1os, ni\u00f1as y adolescentes en el pa\u00eds, mientras sigue en curso la investigaci\u00f3n por las desapariciones&nbsp;Loan Danilo Pe\u00f1a&nbsp;y&nbsp;Lian Gael Flores Soraire, los dos casos m\u00e1s resonantes de los \u00faltimos meses.<\/p>\n\n\n\n<p>\u201cEs alarmante, y hay que pensar que recibimos parte reducida de las denuncias que se producen en el pa\u00eds, porque no todas las denuncias nos llegan.&nbsp;Hay mucho m\u00e1s de seis denuncias por d\u00eda. Es un promedio, todos los d\u00edas var\u00eda\u201d, revel\u00f3 Llobet.<\/p>\n\n\n\n<p>Actualmente, seg\u00fan Llobet, la ONG tiene&nbsp;42 b\u00fasquedas activas&nbsp;de ni\u00f1os que permanecen desaparecidos, y de los cuales no se tiene informaci\u00f3n alguna. \u201cUno puede suponer que hubo detr\u00e1s alg\u00fan&nbsp;delito de trata, pero siempre estamos en el terreno de las hip\u00f3tesis\u201d, puntualiz\u00f3 la presidenta de la organizaci\u00f3n.<\/p>\n\n\n\n<p>Llobet hizo un llamado a las familias para que, en cuanto sospechen que su hijo no est\u00e1 donde deber\u00eda estar, hagan la denuncia de inmediato en lo que se define como \u201cla hora de oro\u201d. \u201cEn la primera hora que se pierde un ni\u00f1o, puede ser encontrado en su contexto habitual\u201d, consider\u00f3, en di\u00e1logo con radio&nbsp;Mitre. Fue lo que no sucedi\u00f3 en el caso de Liam Flores, seg\u00fan la vocera, donde hubo una demora en realizar la denuncia.<\/p>\n\n\n\n<p>Llobet tambi\u00e9n destac\u00f3 la labor de la organizaci\u00f3n, que se encarga de la b\u00fasqueda de los menores desaparecidos. \u201cNosotros nos ocupamos de la b\u00fasqueda de los chicos, y nuestra tarea termina cuando los chicos son encontrados\u201d, indic\u00f3. No obstante, expres\u00f3 que resulta dif\u00edcil determinar las causas del extrav\u00edo, una vez que los menores son localizados. \u201cMuchas veces no sabemos qu\u00e9 les pas\u00f3, porque las familias a veces no cuentan y no tenemos derecho a exigir ning\u00fan tipo de explicaci\u00f3n\u201d, apunt\u00f3.<\/p>\n\n\n\n<p>En cuanto a las estrategias de comunicaci\u00f3n, Llobet destac\u00f3 que la organizaci\u00f3n se apoya en las redes sociales para llegar a un mayor n\u00famero de personas. \u201cNos manejamos a trav\u00e9s de redes, Twitter, Instagram y Facebook, que tenemos el tel\u00e9fono oficial de Missing Children, a donde la gente se puede comunicar para pedir asesoramiento, ayuda, y sobre todo para pedir datos\u201d, explic\u00f3. Adem\u00e1s, mencion\u00f3 que reciben solicitudes de colaboraci\u00f3n por parte de los organismos judiciales o de las propias familias.<\/p>\n\n\n\n<p>En relaci\u00f3n sobre trata con fines de&nbsp;tr\u00e1fico de \u00f3rganos, Llobet dej\u00f3 claro que, pese a haber gestionado \u201cm\u00e1s de 18,900 casos\u201d, nunca se corrobor\u00f3 un hecho de este tipo. \u201cNunca tuvimos un caso de tr\u00e1fico de \u00f3rganos. Los que est\u00e1n sin resolver, no sabemos\u201d, expres\u00f3. Llobet tambi\u00e9n aclar\u00f3 que consultaron con el Instituto Nacional Central \u00danico Coordinador de Ablaci\u00f3n e Implante (INCUCAI) por el tema. \u201cEs sumamente dif\u00edcil sacar un \u00f3rgano; requiere de una planificaci\u00f3n absoluta y el receptor adecuado de ese \u00f3rgano\u201d, explic\u00f3, con la intenci\u00f3n de disipar las dudas que circulan sobre estos temas.<\/p>\n\n\n\n<p>En la causa de&nbsp;Loan Danilo Pe\u00f1a, el ni\u00f1o que ten\u00eda 5 a\u00f1os cuando desapareci\u00f3 en Corrientes el 13 de junio de 2024, se encuentran detenidas varias personas y polic\u00edas por estar involucrados en su desaparici\u00f3n. Ayer, la familia emiti\u00f3 un comunicado en el que pidi\u00f3 que contin\u00fae la b\u00fasqueda para \u201cllevarlo de nuevo a casa\u201d.<\/p>\n\n\n\n<p>El otro caso que tuvo repercusi\u00f3n reciente es el de&nbsp;Lian Gael Flores, de tres a\u00f1os. Fue visto por \u00faltima vez el s\u00e1bado 22 de febrero a las 15.30 en un cortadero de ladrillos ubicado en&nbsp;Ballesteros Sud, provincia de C\u00f3rdoba.<\/p>\n\n\n\n<p>Guadalupe Lucero, una ni\u00f1a cordobesa de cinco a\u00f1os que desapareci\u00f3 el 14 de junio de 2021 en San Luis y cuyo paradero, sigue siendo un misterio. Lo mismo ocurre con el de&nbsp;Sof\u00eda Herrera, vista por \u00faltima vez en un camping de&nbsp;R\u00edo Grande, en la provincia de Tierra del Fuego, el 28 de septiembre de 2008.<\/p>\n\n\n\n<p>De acuerdo a un informe conjunto de la Organizaci\u00f3n Internacional para las Migraciones (OIM), la Organizaci\u00f3n Internacional del Trabajo (OIT) y la fundaci\u00f3n Walk Free, existen hoy en d\u00eda&nbsp;50 millones de v\u00edctimas de trata en el mundo, siendo el 30% de ellas ni\u00f1os y ni\u00f1as.<\/p>\n\n\n\n<p>El Gobierno nacional tiene a disposici\u00f3n la&nbsp;L\u00ednea 124, que centraliza en una base de datos informaci\u00f3n de todo el pa\u00eds sobre ni\u00f1os, ni\u00f1as y adolescentes de quienes se desconozca el paradero. Tambi\u00e9n se puede comunicar al 0800-122-2442 o escribir al correo electr\u00f3nico juschicos@jus.gov.ar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A poco de cumplirse un a\u00f1o de la desaparici\u00f3n de Loan Pe\u00f1a, la ONG destac\u00f3<\/p>\n","protected":false},"author":1,"featured_media":1619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1618"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1618"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1618\/revisions"}],"predecessor-version":[{"id":1620,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1618\/revisions\/1620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1619"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}