{"id":1698,"date":"2025-07-28T14:53:10","date_gmt":"2025-07-28T14:53:10","guid":{"rendered":"https:\/\/nordesteinfo.com\/?p=1698"},"modified":"2025-07-28T14:53:10","modified_gmt":"2025-07-28T14:53:10","slug":"temporal-de-lluvia-y-granizo-provoco-caida-de-arboles-y-postes","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2025\/07\/28\/temporal-de-lluvia-y-granizo-provoco-caida-de-arboles-y-postes\/","title":{"rendered":"TEMPORAL DE LLUVIA Y GRANIZO PROVOC\u00d3 CA\u00cdDA DE \u00c1RBOLES Y POSTES"},"content":{"rendered":"\n<p>La tormenta sorprendi\u00f3 a los vecinos durante la noche del s\u00e1bado. En solo media hora, fuertes r\u00e1fagas, granizo de distintos tama\u00f1os y una intensa lluvia generaron numerosos inconvenientes en la ciudad. A\u00fan se eval\u00faan los da\u00f1os.<\/p>\n\n\n\n<p>Un fuerte temporal de lluvia y granizo azot\u00f3 la ciudad de Corrientes durante la noche del&nbsp;<strong>s\u00e1bado 26 de julio<\/strong>, dejando como saldo \u00e1rboles ca\u00eddos, postes de energ\u00eda derribados, calles anegadas y da\u00f1os materiales en distintas zonas de la capital provincial.<\/p>\n\n\n\n<p>El fen\u00f3meno se registr\u00f3 alrededor de las 23:02 y se extendi\u00f3 por aproximadamente media hora. En ese lapso, vecinos de distintos barrios reportaron granizos de distintos tama\u00f1os, algunos de ellos de gran dimensi\u00f3n, que provocaron<strong>&nbsp;da\u00f1os en techos, veh\u00edculos y estructuras al aire libre.<\/strong><\/p>\n\n\n\n<p>Las r\u00e1fagas de viento y la ca\u00edda de agua fueron de tal intensidad que, en pocos minutos, varias calles se vieron completamente cubiertas de agua, dificultando el tr\u00e1nsito vehicular y peatonal. Adem\u00e1s,&nbsp;<strong>la ca\u00edda de cables el\u00e9ctricos y ramas<\/strong>&nbsp;oblig\u00f3 a interrumpir moment\u00e1neamente la circulaci\u00f3n en algunas zonas.<\/p>\n\n\n\n<p>Vecinos compartieron im\u00e1genes y videos en redes sociales donde se puede observar la magnitud, que en algunos sectores se sinti\u00f3 con mayor fuerza. Bomberos y personal municipal comenzaron desde temprano con las&nbsp;<strong>tareas de limpieza, remoci\u00f3n de escombros y asistencia.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tormenta sorprendi\u00f3 a los vecinos durante la noche del s\u00e1bado. En solo media hora,<\/p>\n","protected":false},"author":1,"featured_media":1699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1698"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=1698"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1698\/revisions"}],"predecessor-version":[{"id":1700,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/1698\/revisions\/1700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media\/1699"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=1698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=1698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=1698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}