{"id":480,"date":"2023-01-13T15:20:24","date_gmt":"2023-01-13T15:20:24","guid":{"rendered":"http:\/\/nordesteinfo.com\/?p=480"},"modified":"2023-01-13T15:20:25","modified_gmt":"2023-01-13T15:20:25","slug":"socorrieron-a-un-guia-de-pesca-tras-sufrir-un-preinfarto-mientras-navegaba","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2023\/01\/13\/socorrieron-a-un-guia-de-pesca-tras-sufrir-un-preinfarto-mientras-navegaba\/","title":{"rendered":"SOCORRIERON A UN GU\u00cdA DE PESCA TRAS SUFRIR UN PREINFARTO MIENTRAS NAVEGABA"},"content":{"rendered":"\n<p>El hombre fue asistido de inmediato.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2023\/01\/1673607238593.webp\" alt=\"\" class=\"wp-image-481\"\/><\/figure>\n\n\n\n<p>Socorrieron a un gu\u00eda de pesca que sufri\u00f3 un pre infarto mientras navegaba por el R\u00edo Paran\u00e1, informaron este viernes desde la Polic\u00eda de Corrientes.&nbsp;<\/p>\n\n\n\n<p>Un hombre fue rescatado por personal\u00a0de la Polic\u00eda Rural y personal de la Direcci\u00f3n de Fauna tras un sufrir un pre infarto cerca del denominado kil\u00f3metro 15 del R\u00edo Paran\u00e1 al norte de la Capital correntina.\u00a0<\/p>\n\n\n\n<p>Seg\u00fan detallaron, el gu\u00eda se encontraba navegando cuando sufri\u00f3 el&nbsp;episodio y tras padecer tambi\u00e9n riesgo de un accidente cerebro vascular un chico y un hombre que presenciaron el hecho advirtieron a las autoridades del lugar.<\/p>\n\n\n\n<p>De esta forma los cabos&nbsp;&nbsp;primero Maximiliano S\u00e1nchez y el sargento Lucio G\u00f3mez junto a los&nbsp;inspectores Ra\u00fal Barrientos y Ram\u00f3n S\u00e1nchez&nbsp;&nbsp;procedieron a auxiliar de inmediato al hombre sobre una lancha.<\/p>\n\n\n\n<p>Tras maniobras de reanimaci\u00f3n lograron estabilizarlo y llevar a tierra firme hasta la llegada de una ambulancia con personal sanitario.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hombre fue asistido de inmediato.\u00a0 Socorrieron a un gu\u00eda de pesca que sufri\u00f3 un<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-480","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/480"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=480"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/480\/revisions"}],"predecessor-version":[{"id":482,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/480\/revisions\/482"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}