{"id":563,"date":"2023-03-30T12:39:24","date_gmt":"2023-03-30T12:39:24","guid":{"rendered":"http:\/\/nordesteinfo.com\/?p=563"},"modified":"2023-03-30T12:39:25","modified_gmt":"2023-03-30T12:39:25","slug":"les-robaron-un-iphone-a-punta-de-cuchillo","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2023\/03\/30\/les-robaron-un-iphone-a-punta-de-cuchillo\/","title":{"rendered":"LES ROBARON UN IPHONE A PUNTA DE CUCHILLO"},"content":{"rendered":"\n<p>Las v\u00edctimas alcanzaron a reconocer a uno de los malvivientes, quien sali\u00f3 de estar en prisi\u00f3n por el mismo delito. El pueblo volvi\u00f3 a exigir seguridad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2023\/03\/1285222w850h879c.jpg.webp\" alt=\"\" class=\"wp-image-564\"\/><\/figure>\n\n\n\n<p>Dos j\u00f3venes que se hallaban en el interior de un autom\u00f3vil en el barrio Florida de la ciudad de Monte Caseros, fueron v\u00edctimas de un robo violento, luego de que cuatro delincuentes portando cuchillos los amenazaran y uno de ellos los atacara a puntazos para robarle su celular. Uno de los atacantes sali\u00f3 recientemente de prisi\u00f3n. El hecho pasa en el medio de una convulsi\u00f3n social por los reiterados casos de inseguridad que viene padeciendo aquella ciudad y que tuvo much\u00edsimas personas lesionadas a cuchillazos, golpes y balazos.<\/p>\n\n\n\n<p>El hecho sucedi\u00f3 el mi\u00e9rcoles por la noche, cerca del barrio Florida. Lautaro y su amigo se encontraban conversando dentro de un autom\u00f3vil, cuando los cercaron cuatro sujetos, uno de ellos fue reconocido por las v\u00edctimas, tiene un extenso prontuario delictivo y adem\u00e1s recientemente sali\u00f3 de prisi\u00f3n.<\/p>\n\n\n\n<p>Seg\u00fan contaron las v\u00edctimas, uno de los delincuentes, lanz\u00f3 un puntazo sobre Lautaro, quien logr\u00f3 esquivar el arma blanca y ya sin posibilidades ni alternativas ante el accionar delictivo, ambos j\u00f3venes entregaron los celulares, uno de ellos, un Iphone y la llave del comercio.<\/p>\n\n\n\n<p>Los j\u00f3venes radicaron la denuncia ante sede policial y reconocieron a los delincuentes, por lo que se espera su detenci\u00f3n en las pr\u00f3ximas horas.<\/p>\n\n\n\n<p>Anoche en tanto, decenas de personas participaron de una reuni\u00f3n abierta en la \u00abCasa del Bicentenario\u00bb de Monte Caseros, donde adem\u00e1s estuvieron autoridades policiales y pol\u00edticas de la ciudad. All\u00ed, las fuerzas vivas locales volvieron a exigir mayor seguridad. Antes se hab\u00eda realizado un acto en el que entregaron m\u00f3viles y materiales de seguridad para la Comisar\u00eda Primera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las v\u00edctimas alcanzaron a reconocer a uno de los malvivientes, quien sali\u00f3 de estar en<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-563","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/563"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=563"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/563\/revisions"}],"predecessor-version":[{"id":565,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/563\/revisions\/565"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}