{"id":696,"date":"2023-05-18T14:15:19","date_gmt":"2023-05-18T14:15:19","guid":{"rendered":"http:\/\/nordesteinfo.com\/?p=696"},"modified":"2023-05-18T14:15:20","modified_gmt":"2023-05-18T14:15:20","slug":"desarticularon-una-banda-de-remiseros-narcos-en-goya","status":"publish","type":"post","link":"https:\/\/nordesteinfo.com\/index.php\/2023\/05\/18\/desarticularon-una-banda-de-remiseros-narcos-en-goya\/","title":{"rendered":"DESARTICULARON UNA BANDA DE \u00abREMISEROS NARCOS\u00bb EN GOYA"},"content":{"rendered":"\n<p>Las fincas requisadas estaban en la zona c\u00e9ntrica y en cuatro barrios de la ciudad. Adem\u00e1s de droga, hallaron armas de fuego y una fuerte suma de dinero. Hay cinco detenidos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/nordesteinfo.com\/wp-content\/uploads\/2023\/05\/1294314w762h712c.jpg.webp\" alt=\"\" class=\"wp-image-697\"\/><\/figure>\n\n\n\n<p>Una importante cantidad de dinero, droga, armas de fuego y municiones, fue el resultado de por lo menos seis allanamientos realizados por efectivos de la Polic\u00eda Federal Argentina en la ciudad de Goya, que permiti\u00f3 desarticular una banda de remiseros, que desde hace un tiempo ven\u00eda comercializando estupefaciente al menudeo, informaron fuentes oficiales.<\/p>\n\n\n\n<p>Los allanamientos fueron ordenados por la juez federal de Goya, Cristina Elizabet Pozzer Penzo, y concretados por efectivos de la Divisi\u00f3n Unidad Operativa Federal de esa fuerza, con asiento en la segunda ciudad de la provincia.<\/p>\n\n\n\n<p>Seg\u00fan indicaron fuentes de la investigaci\u00f3n, los allanamientos se concretaron en las primeras horas del s\u00e1bado, en la zona c\u00e9ntrica de la ciudad y en los barrios Devoto, Mariano Moreno, Villa Sc\u00f3fano y Mauricio Valenzuela, donde la Polic\u00eda encontr\u00f3 una importante cantidad de marihuana y coca\u00edna, en trozo y fraccionada listas para la venta. Tambi\u00e9n incautaron dos armas de fuego de grueso calibre, as\u00ed como municiones para las mismas y para escopeta; elementos de corte, fraccionamiento, balanzas de precisi\u00f3n, varios tel\u00e9fonos celulares, handys y una fuerte suma de dinero, presuntamente proveniente de la comercializaci\u00f3n de estupefacientes.<\/p>\n\n\n\n<p>La Polic\u00eda Federal tambi\u00e9n decomis\u00f3 tres veh\u00edculos utilizados como remises que eran la principal pantalla de la organizaci\u00f3n y con los que distribu\u00edan la droga a distintos puntos de la ciudad de Goya.<\/p>\n\n\n\n<p>Fueron cinco las personas detenidas en el marco de la investigaci\u00f3n y los allanamientos se realizaron aprovechando el marco de la 46\u00b0 Fiesta Nacional del Surub\u00ed, ya que los acusados estaban con intensa actividad y se pudo comprobar sus movimiento con los turistas que llegaron de a miles a esa ciudad.<\/p>\n\n\n\n<p>Fuentes allegadas a la investigaci\u00f3n, revelaron a diario \u00e9poca que desde hace meses la Polic\u00eda y la Justicia federal estaban tras esta banda narco que ven\u00eda operando en la venta de estupefaciente al menudeo. Vigilancia, filmaciones y fotograf\u00edas conformar\u00edan parte del expediente. Todos los elementos incautados, as\u00ed como los detenidos durante los allanamientos, fueron puestos a disposici\u00f3n de la Justicia y trasladados a la sede de la Delegaci\u00f3n Goya de la Polic\u00eda Federal Argentina, donde en los pr\u00f3ximo d\u00edas ser\u00e1n llamados a indagatoria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las fincas requisadas estaban en la zona c\u00e9ntrica y en cuatro barrios de la ciudad.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-696","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/696"}],"collection":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/comments?post=696"}],"version-history":[{"count":1,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/696\/revisions"}],"predecessor-version":[{"id":698,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/posts\/696\/revisions\/698"}],"wp:attachment":[{"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/media?parent=696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/categories?post=696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteinfo.com\/index.php\/wp-json\/wp\/v2\/tags?post=696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}